{"id":246716,"date":"1999-06-25T08:36:00","date_gmt":"1999-06-25T00:36:00","guid":{"rendered":"https:\/\/articles.ricacorp.com\/?p=246716"},"modified":"2019-02-20T17:54:23","modified_gmt":"2019-02-20T09:54:23","slug":"%e8%90%bd%e6%88%90%e9%87%8f%e6%9c%89%e5%88%a5%e6%96%bc%e9%96%8b%e7%9b%a4%e9%87%8f","status":"publish","type":"post","link":"https:\/\/www.ricacorp.com.cn\/articles\/1999\/06\/25\/%e8%90%bd%e6%88%90%e9%87%8f%e6%9c%89%e5%88%a5%e6%96%bc%e9%96%8b%e7%9b%a4%e9%87%8f\/","title":{"rendered":"\u843d\u6210\u91cf\u6709\u5225\u65bc\u958b\u76e4\u91cf"},"content":{"rendered":"<p>\u5dee&nbsp;\u9909&nbsp;\u7269&nbsp;\u696d&nbsp;\u4f30&nbsp;\u50f9&nbsp;\u7f72&nbsp;\u51fa&nbsp;\u7684&nbsp;\u201c&nbsp;\u9999&nbsp;\u6e2f&nbsp;\u7269&nbsp;\u696d&nbsp;\u5831&nbsp;\u544a&nbsp;\u201d&nbsp;\uff0c&nbsp;\u9810&nbsp;\u671f&nbsp;\u4e5d&nbsp;\u4e5d&nbsp;\u5e74&nbsp;\u79c1&nbsp;\u4eba&nbsp;\u4f4f&nbsp;\u5b85&nbsp;\u7684&nbsp;\u843d&nbsp;\u6210&nbsp;\u91cf&nbsp;\u9ad8&nbsp;\u9054&nbsp;\u4e09&nbsp;\u842c&nbsp;\u516d&nbsp;\u5343&nbsp;\u4e00&nbsp;\u767e&nbsp;\u500b&nbsp;\uff0c&nbsp;\u6bd4&nbsp;\u4e5d&nbsp;\u516b&nbsp;\u5e74&nbsp;\u7684&nbsp;\u4e8c&nbsp;\u842c&nbsp;\u4e8c&nbsp;\u5343&nbsp;\u4e8c&nbsp;\u767e&nbsp;\u516b&nbsp;\u5341&nbsp;\u500b&nbsp;\u591a&nbsp;\u4e86&nbsp;\u767e&nbsp;\u5206&nbsp;\u4e4b&nbsp;\u516d&nbsp;\u5341&nbsp;\u4e8c&nbsp;\u3002&nbsp;\u6709&nbsp;\u4e9b&nbsp;\u884c&nbsp;\u5bb6&nbsp;\u53ca&nbsp;\u50b3&nbsp;\u5a92&nbsp;\u90fd&nbsp;\u501f&nbsp;\u6b64&nbsp;\u5927&nbsp;\u505a&nbsp;\u6587&nbsp;\u7ae0&nbsp;\uff0c&nbsp;\u8a8d&nbsp;\u70ba&nbsp;\u9019&nbsp;\u9ebc&nbsp;\u5927&nbsp;\u7684&nbsp;\u4f9b&nbsp;\u61c9&nbsp;\u91cf&nbsp;\u5c07&nbsp;\u5c0d&nbsp;\u4eca&nbsp;\u5e74&nbsp;\u7684&nbsp;\u5730&nbsp;\u7522&nbsp;\u5e02&nbsp;\u9053&nbsp;\u9020&nbsp;\u6210&nbsp;\u58d3&nbsp;\u529b&nbsp;\uff0c&nbsp;\u6211&nbsp;\u5c0d&nbsp;\u6b64&nbsp;\u5247&nbsp;\u4e0d&nbsp;\u592a&nbsp;\u64d4&nbsp;\u5fc3&nbsp;\u3002&nbsp;\u4eba&nbsp;\u5011&nbsp;\u4e4b&nbsp;\u6240&nbsp;\u4ee5&nbsp;\u6709&nbsp;\u6b64&nbsp;\u64d4&nbsp;\u5fc3&nbsp;\uff0c&nbsp;\u4e3b&nbsp;\u8981&nbsp;\u662f&nbsp;\u56e0&nbsp;\u70ba&nbsp;\u4e0d&nbsp;\u660e&nbsp;\u767d&nbsp;\u5dee&nbsp;\u9909&nbsp;\u7269&nbsp;\u696d&nbsp;\u4f30&nbsp;\u50f9&nbsp;\u7f72&nbsp;\u6240&nbsp;\u8aaa&nbsp;\u7684&nbsp;\u4f9b&nbsp;\u61c9&nbsp;\uff0c&nbsp;\u5176&nbsp;\u5be6&nbsp;\u662f&nbsp;\u6307&nbsp;\u7269&nbsp;\u696d&nbsp;\u5177&nbsp;\u9ad4&nbsp;\u8208&nbsp;\u5efa&nbsp;\u843d&nbsp;\u6210&nbsp;\uff0c&nbsp;\u53ef&nbsp;\u771f&nbsp;\u6b63&nbsp;\u4f9b&nbsp;\u4eba&nbsp;\u5c45&nbsp;\u4f4f&nbsp;\u7684&nbsp;\u4f9b&nbsp;\u61c9&nbsp;\uff0c&nbsp;\u800c&nbsp;\u4e0d&nbsp;\u662f&nbsp;\u62ff&nbsp;\u51fa&nbsp;\u5e02&nbsp;\u5834&nbsp;\u92b7&nbsp;\u552e&nbsp;\u7684&nbsp;\u90a3&nbsp;\u7a2e&nbsp;\u4f9b&nbsp;\u61c9&nbsp;\u3002&nbsp;<br>\n\u81ea&nbsp;\u5f9e&nbsp;\u653f&nbsp;\u5e9c&nbsp;\u653e&nbsp;\u5bec&nbsp;\u6a13&nbsp;\u82b1&nbsp;\u958b&nbsp;\u76e4&nbsp;\u7684&nbsp;\u6642&nbsp;\u9593&nbsp;\u9650&nbsp;\u5236&nbsp;\u5f8c&nbsp;\uff0c&nbsp;\u767c&nbsp;\u5c55&nbsp;\u5546&nbsp;\u5df2&nbsp;\u53ef&nbsp;\u5728&nbsp;\u6a13&nbsp;\u5b87&nbsp;\u5165&nbsp;\u4f19&nbsp;\u524d&nbsp;\u4e8c&nbsp;\u5341&nbsp;\u500b&nbsp;\u6708&nbsp;\u4e4b&nbsp;\u5167&nbsp;\u9078&nbsp;\u64c7&nbsp;\u958b&nbsp;\u76e4&nbsp;\u3002&nbsp;\u5373&nbsp;\u662f&nbsp;\u8aaa&nbsp;\uff0c&nbsp;\u5982&nbsp;\u679c&nbsp;\u6a13&nbsp;\u82b1&nbsp;\u92b7&nbsp;\u552e&nbsp;\u7406&nbsp;\u60f3&nbsp;\u7684&nbsp;\u8a71&nbsp;\uff0c&nbsp;\u5230&nbsp;\u6a13&nbsp;\u5b87&nbsp;\u5165&nbsp;\u4f19&nbsp;\u6642&nbsp;\uff0c&nbsp;\u53ef&nbsp;\u80fd&nbsp;\u5927&nbsp;\u90e8&nbsp;\u5206&nbsp;\u55ae&nbsp;\u4f4d&nbsp;\u5176&nbsp;\u5be6&nbsp;\u5df2&nbsp;\u7d93&nbsp;\u8ce3&nbsp;\u51fa&nbsp;\uff0c&nbsp;\u4e0d&nbsp;\u6703&nbsp;\u5c0d&nbsp;\u5e02&nbsp;\u5834&nbsp;\u9020&nbsp;\u6210&nbsp;\u58d3&nbsp;\u529b&nbsp;\u3002&nbsp;<br>\n\u904e&nbsp;\u5f80&nbsp;\u7092&nbsp;\u98a8&nbsp;\u71be&nbsp;\u71b1&nbsp;\u6642&nbsp;\uff0c&nbsp;\u6a13&nbsp;\u82b1&nbsp;\u7684&nbsp;\u8cb7&nbsp;\u5bb6&nbsp;\u53ef&nbsp;\u80fd&nbsp;\u672a&nbsp;\u5fc5&nbsp;\u662f&nbsp;\u771f&nbsp;\u6b63&nbsp;\u7684&nbsp;\u7528&nbsp;\u5bb6&nbsp;\uff0c&nbsp;\u52a0&nbsp;\u4e0a&nbsp;\u6709&nbsp;\u4e00&nbsp;\u500b&nbsp;\u6642&nbsp;\u671f&nbsp;\u653f&nbsp;\u5e9c&nbsp;\u9650&nbsp;\u5236&nbsp;\u6a13&nbsp;\u82b1&nbsp;\u671f&nbsp;\u7684&nbsp;\u8f49&nbsp;\u552e&nbsp;\u6d3b&nbsp;\u52d5&nbsp;\uff0c&nbsp;\u4ee5&nbsp;\u81f3&nbsp;\u6a13&nbsp;\u82b1&nbsp;\u5165&nbsp;\u4f19&nbsp;\u521d&nbsp;\u6bb5&nbsp;\uff0c&nbsp;\u7092&nbsp;\u5bb6&nbsp;\u90fd&nbsp;\u96c6&nbsp;\u4e2d&nbsp;\u5728&nbsp;\u9019&nbsp;\u6bb5&nbsp;\u6642&nbsp;\u9593&nbsp;\u653e&nbsp;\u76e4&nbsp;\uff0c&nbsp;\u6545&nbsp;\u6a13&nbsp;\u5b87&nbsp;\u843d&nbsp;\u6210&nbsp;\u91cf&nbsp;\u5927&nbsp;\u4ea6&nbsp;\u6703&nbsp;\u5c0d&nbsp;\u5e02&nbsp;\u5834&nbsp;\u9020&nbsp;\u6210&nbsp;\u58d3&nbsp;\u529b&nbsp;\u3002&nbsp;\u4e5d&nbsp;\u516b&nbsp;\u5e74&nbsp;\u5c31&nbsp;\u662f&nbsp;\u9019&nbsp;\u7a2e&nbsp;\u60c5&nbsp;\u6cc1&nbsp;\u8f03&nbsp;\u70ba&nbsp;\u56b4&nbsp;\u91cd&nbsp;\u7684&nbsp;\u4e00&nbsp;\u5e74&nbsp;\uff0c&nbsp;\u56e0&nbsp;\u70ba&nbsp;\u7092&nbsp;\u5bb6&nbsp;\u4e0d&nbsp;\u4f46&nbsp;\u5728&nbsp;\u6a13&nbsp;\u5b87&nbsp;\u843d&nbsp;\u6210&nbsp;\u6642&nbsp;\u5927&nbsp;\u91cf&nbsp;\u653e&nbsp;\u76e4&nbsp;\uff0c&nbsp;\u4e26&nbsp;\u4e14&nbsp;\u5927&nbsp;\u91cf&nbsp;\u64bb&nbsp;\u5b9a&nbsp;\uff0c&nbsp;\u4ee4&nbsp;\u767c&nbsp;\u5c55&nbsp;\u5546&nbsp;\u9664&nbsp;\u4e86&nbsp;\u8981&nbsp;\u958b&nbsp;\u65b0&nbsp;\u76e4&nbsp;\u5916&nbsp;\uff0c&nbsp;\u9084&nbsp;\u8981&nbsp;\u8a2d&nbsp;\u6cd5&nbsp;\u63a8&nbsp;\u92b7&nbsp;\u64bb&nbsp;\u5b9a&nbsp;\u55ae&nbsp;\u4f4d&nbsp;\uff0c&nbsp;\u518d&nbsp;\u52a0&nbsp;\u4e0a&nbsp;\u6709&nbsp;\u4eba&nbsp;\u8e22&nbsp;\u5951&nbsp;\u6216&nbsp;\u5229&nbsp;\u7528&nbsp;\u653f&nbsp;\u5ba2&nbsp;\u641e&nbsp;\u904a&nbsp;\u884c&nbsp;\u8acb&nbsp;\u9858&nbsp;\uff0c&nbsp;\u91c0&nbsp;\u6210&nbsp;\u793e&nbsp;\u6703&nbsp;\u4e8b&nbsp;\u4ef6&nbsp;\uff0c&nbsp;\u7684&nbsp;\u78ba&nbsp;\u5728&nbsp;\u6a13&nbsp;\u5b87&nbsp;\u843d&nbsp;\u6210&nbsp;\u671f&nbsp;\u5c0d&nbsp;\u6a13&nbsp;\u5e02&nbsp;\u9020&nbsp;\u6210&nbsp;\u58d3&nbsp;\u529b&nbsp;\u3002&nbsp;<br>\n\u4e0d&nbsp;\u904e&nbsp;\uff0c&nbsp;\u9019&nbsp;\u7a2e&nbsp;\u60c5&nbsp;\u6cc1&nbsp;\u61c9&nbsp;\u4e0d&nbsp;\u6703&nbsp;\u518d&nbsp;\u5728&nbsp;\u4e5d&nbsp;\u4e5d&nbsp;\u5e74&nbsp;\u51fa&nbsp;\u73fe&nbsp;\u3002&nbsp;\u4e5d&nbsp;\u4e5d&nbsp;\u5e74&nbsp;\u843d&nbsp;\u6210&nbsp;\u6a13&nbsp;\u5b87&nbsp;\uff0c&nbsp;\u76f8&nbsp;\u7576&nbsp;\u5927&nbsp;\u7684&nbsp;\u90e8&nbsp;\u5206&nbsp;\u5df2&nbsp;\u5728&nbsp;\u6a13&nbsp;\u82b1&nbsp;\u671f&nbsp;\u9810&nbsp;\u552e&nbsp;\uff0c&nbsp;\u8cb7&nbsp;\u5bb6&nbsp;\u4e2d&nbsp;\u5927&nbsp;\u90e8&nbsp;\u5206&nbsp;\u90fd&nbsp;\u662f&nbsp;\u7528&nbsp;\u5bb6&nbsp;\uff0c&nbsp;\u5728&nbsp;\u5165&nbsp;\u4f19&nbsp;\u5f8c&nbsp;\u7acb&nbsp;\u5373&nbsp;\u60f3&nbsp;\u812b&nbsp;\u624b&nbsp;\u7684&nbsp;\u4eba&nbsp;\u61c9&nbsp;\u5927&nbsp;\u91cf&nbsp;\u6e1b&nbsp;\u5c11&nbsp;\u3002&nbsp;\u6cc1&nbsp;\u4e14&nbsp;\uff0c&nbsp;\u9019&nbsp;\u6279&nbsp;\u5c07&nbsp;\u5165&nbsp;\u4f19&nbsp;\u7684&nbsp;\u6a13&nbsp;\u5b87&nbsp;\uff0c&nbsp;\u5927&nbsp;\u90e8&nbsp;\u5206&nbsp;\u662f&nbsp;\u5728&nbsp;\u4f4e&nbsp;\u6f6e&nbsp;\u6642&nbsp;\u671f&nbsp;\u958b&nbsp;\u76e4&nbsp;\uff0c&nbsp;\u5230&nbsp;\u771f&nbsp;\u6b63&nbsp;\u5165&nbsp;\u4f19&nbsp;\u6642&nbsp;\uff0c&nbsp;\u8cb7&nbsp;\u5bb6&nbsp;\u5df2&nbsp;\u53ef&nbsp;\u7372&nbsp;\u5fae&nbsp;\u5229&nbsp;\uff0c&nbsp;\u4e0d&nbsp;\u6703&nbsp;\u6709&nbsp;\u4eba&nbsp;\u9700&nbsp;\u8981&nbsp;\u64bb&nbsp;\u5b9a&nbsp;\u6216&nbsp;\u8e22&nbsp;\u5951&nbsp;\uff0c&nbsp;\u56e0&nbsp;\u70ba&nbsp;\u4e0d&nbsp;\u60f3&nbsp;\u8981&nbsp;\u7684&nbsp;\u4eba&nbsp;\u5f88&nbsp;\u5bb9&nbsp;\u6613&nbsp;\u53ef&nbsp;\u5728&nbsp;\u4e8c&nbsp;\u624b&nbsp;\u5e02&nbsp;\u5834&nbsp;\u6210&nbsp;\u529f&nbsp;\u627e&nbsp;\u5230&nbsp;\u8cb7&nbsp;\u5bb6&nbsp;\u63a5&nbsp;\u624b&nbsp;\uff0c&nbsp;\u4e0d&nbsp;\u7528&nbsp;\u51fa&nbsp;\u6b64&nbsp;\u4e0b&nbsp;\u7b56&nbsp;\uff0c&nbsp;\u51fa&nbsp;\u73fe&nbsp;\u64bb&nbsp;\u5b9a&nbsp;\u6f6e&nbsp;\u6216&nbsp;\u8e22&nbsp;\u5951&nbsp;\u6f6e&nbsp;\u7684&nbsp;\u5ba2&nbsp;\u89c0&nbsp;\u74b0&nbsp;\u5883&nbsp;\u5df2&nbsp;\u4e0d&nbsp;\u5b58&nbsp;\u5728&nbsp;\u3002&nbsp;\u56e0&nbsp;\u6b64&nbsp;\uff0c&nbsp;\u6211&nbsp;\u4e0d&nbsp;\u76f8&nbsp;\u4fe1&nbsp;\u5e02&nbsp;\u5834&nbsp;\u6703&nbsp;\u56e0&nbsp;\u4e5d&nbsp;\u4e5d&nbsp;\u5e74&nbsp;\u6a13&nbsp;\u5b87&nbsp;\u7684&nbsp;\u843d&nbsp;\u6210&nbsp;\u91cf&nbsp;\u5927&nbsp;\u6709&nbsp;\u592a&nbsp;\u5927&nbsp;\u7684&nbsp;\u885d&nbsp;\u64ca&nbsp;\u3002&nbsp;<br>\n\u8fd1&nbsp;\u671f&nbsp;\uff0c&nbsp;\u767c&nbsp;\u5c55&nbsp;\u5546&nbsp;\u5728&nbsp;\u571f&nbsp;\u5730&nbsp;\u62cd&nbsp;\u8ce3&nbsp;\u53ca&nbsp;\u6295&nbsp;\u7968&nbsp;\u6642&nbsp;\u5df2&nbsp;\u8f03&nbsp;\u524d&nbsp;\u7a4d&nbsp;\u6975&nbsp;\u9032&nbsp;\u53d6&nbsp;\uff0c&nbsp;\u986f&nbsp;\u793a&nbsp;\u4ed6&nbsp;\u5011&nbsp;\u5c0d&nbsp;\u5f8c&nbsp;\u5e02&nbsp;\u5df2&nbsp;\u6f38&nbsp;\u6062&nbsp;\u5fa9&nbsp;\u4fe1&nbsp;\u5fc3&nbsp;\uff0c&nbsp;\u518d&nbsp;\u6380&nbsp;\u8d77&nbsp;\u5927&nbsp;\u898f&nbsp;\u6a21&nbsp;\u6e1b&nbsp;\u50f9&nbsp;\u6230&nbsp;\u7684&nbsp;\u6a5f&nbsp;\u6703&nbsp;\u61c9&nbsp;\u8a72&nbsp;\u4e0d&nbsp;\u5927&nbsp;\u3002&nbsp;\u56e0&nbsp;\u6b64&nbsp;\uff0c&nbsp;\u6211&nbsp;\u9810&nbsp;\u671f&nbsp;\u4e5d&nbsp;\u4e5d&nbsp;\u5e74&nbsp;\u7684&nbsp;\u6574&nbsp;\u9ad4&nbsp;\u5e02&nbsp;\u9053&nbsp;\u7406&nbsp;\u61c9&nbsp;\u6bd4&nbsp;\u4e5d&nbsp;\u516b&nbsp;\u5e74&nbsp;\u70ba&nbsp;\u4f73&nbsp;\uff0c&nbsp;\u5e74&nbsp;\u5c3e&nbsp;\u6a13&nbsp;\u50f9&nbsp;\u61c9&nbsp;\u7565&nbsp;\u9ad8&nbsp;\u65bc&nbsp;\u5e74&nbsp;\u521d&nbsp;\uff0c&nbsp;\u5347&nbsp;\u5e45&nbsp;\u6709&nbsp;\u6a5f&nbsp;\u6703&nbsp;\u8d85&nbsp;\u904e&nbsp;\u767e&nbsp;\u5206&nbsp;\u4e4b&nbsp;\u5341&nbsp;\u3002&nbsp;\u5927&nbsp;\u5bb6&nbsp;\u4e0d&nbsp;\u7528&nbsp;\u70ba&nbsp;\u4e5d&nbsp;\u4e5d&nbsp;\u5e74&nbsp;\u7684&nbsp;\u843d&nbsp;\u6210&nbsp;\u91cf&nbsp;\u5927&nbsp;\u589e&nbsp;\u800c&nbsp;\u904e&nbsp;\u5206&nbsp;\u64d4&nbsp;\u6182&nbsp;\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u5dee  \u9909  \u7269  \u696d  \u4f30  \u50f9  \u7f72  \u51fa  \u7684  \u201c   \u9999  \u6e2f  \u7269  \u696d  \u5831  \u544a  \u201d<\/p>\n","protected":false},"author":183,"featured_media":240783,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[25703],"tags":[],"class_list":["post-246716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/posts\/246716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/users\/183"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/comments?post=246716"}],"version-history":[{"count":1,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/posts\/246716\/revisions"}],"predecessor-version":[{"id":248299,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/posts\/246716\/revisions\/248299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/media\/240783"}],"wp:attachment":[{"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/media?parent=246716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/categories?post=246716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/tags?post=246716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}