{"id":246692,"date":"1999-05-21T09:15:00","date_gmt":"1999-05-21T01:15:00","guid":{"rendered":"https:\/\/articles.ricacorp.com\/?p=246692"},"modified":"2019-02-21T11:00:19","modified_gmt":"2019-02-21T03:00:19","slug":"%e7%84%a1%e7%82%ba%e8%80%8c%e6%b2%bb","status":"publish","type":"post","link":"https:\/\/www.ricacorp.com.cn\/articles\/1999\/05\/21\/%e7%84%a1%e7%82%ba%e8%80%8c%e6%b2%bb\/","title":{"rendered":"\u7121\u70ba\u800c\u6cbb"},"content":{"rendered":"<p>\u6211&nbsp;\u5e38&nbsp;\u544a&nbsp;\u8a34&nbsp;\u4eba&nbsp;\uff0c&nbsp;\u6211&nbsp;\u4ee5&nbsp;\u7121&nbsp;\u70ba&nbsp;\u800c&nbsp;\u6cbb&nbsp;\u7684&nbsp;\u7406&nbsp;\u5ff5&nbsp;\u4f86&nbsp;\u7ba1&nbsp;\u7406&nbsp;\u4e2d&nbsp;\u539f&nbsp;\uff0c&nbsp;\u4ee5&nbsp;\u81f3&nbsp;\u9054&nbsp;\u5230&nbsp;\u4eca&nbsp;\u5929&nbsp;\u7684&nbsp;\u6210&nbsp;\u7e3e&nbsp;\u3002&nbsp;\u4f46&nbsp;\u807d&nbsp;\u7684&nbsp;\u4eba&nbsp;\u591a&nbsp;\u62b1&nbsp;\u8457&nbsp;\u4e00&nbsp;\u7a2e&nbsp;\u61f7&nbsp;\u7591&nbsp;\u7684&nbsp;\u773c&nbsp;\u5149&nbsp;\u671b&nbsp;\u8457&nbsp;\u6211&nbsp;\u3002&nbsp;\u4ed6&nbsp;\u5011&nbsp;\u6c92&nbsp;\u6cd5&nbsp;\u660e&nbsp;\u767d&nbsp;\uff0c&nbsp;\u4e2d&nbsp;\u539f&nbsp;\u6210&nbsp;\u9577&nbsp;\u5f97&nbsp;\u9019&nbsp;\u9ebc&nbsp;\u5feb&nbsp;\uff0c&nbsp;\u4f5c&nbsp;\u4e86&nbsp;\u9019&nbsp;\u591a&nbsp;\u7684&nbsp;\u4e8b&nbsp;\uff0c&nbsp;\u9019&nbsp;\u600e&nbsp;\u53ef&nbsp;\u4ee5&nbsp;\u53eb&nbsp;\u7121&nbsp;\u70ba&nbsp;\uff1f&nbsp;\uff01&nbsp;\u65bd&nbsp;\u6c38&nbsp;\u9752&nbsp;\u4e00&nbsp;\u5b9a&nbsp;\u5728&nbsp;\u5439&nbsp;\u5653&nbsp;\u800c&nbsp;\u5df2&nbsp;\u3002&nbsp;\u5176&nbsp;\u5be6&nbsp;\uff0c&nbsp;\u6211&nbsp;\u5168&nbsp;\u7121&nbsp;\u5439&nbsp;\u5653&nbsp;\u7684&nbsp;\u610f&nbsp;\u601d&nbsp;\u3002&nbsp;\u6211&nbsp;\u5c0d&nbsp;\u7121&nbsp;\u70ba&nbsp;\u800c&nbsp;\u6cbb&nbsp;\u7684&nbsp;\u4fe1&nbsp;\u5ff5&nbsp;\u662f&nbsp;\u771f&nbsp;\u8aa0&nbsp;\u7684&nbsp;\uff0c&nbsp;\u662f&nbsp;\u8cab&nbsp;\u5207&nbsp;\u59cb&nbsp;\u7d42&nbsp;\u7684&nbsp;\uff0c&nbsp;\u4e26&nbsp;\u975e&nbsp;\u53ea&nbsp;\u662f&nbsp;\u6a19&nbsp;\u699c&nbsp;\u4e00&nbsp;\u4e0b&nbsp;\u5c31&nbsp;\u7b97&nbsp;\u6578&nbsp;\u7684&nbsp;\u3002&nbsp;<br>\n\u6240&nbsp;\u8b02&nbsp;\u7121&nbsp;\u70ba&nbsp;\uff0c&nbsp;\u5c31&nbsp;\u662f&nbsp;\u8981&nbsp;\u77e5&nbsp;\u9053&nbsp;\u500b&nbsp;\u4eba&nbsp;\u7684&nbsp;\u80fd&nbsp;\u529b&nbsp;\u662f&nbsp;\u6709&nbsp;\u5c40&nbsp;\u9650&nbsp;\u7684&nbsp;\uff0c&nbsp;\u6545&nbsp;\u5fc5&nbsp;\u9808&nbsp;\u5c0a&nbsp;\u91cd&nbsp;\u5929&nbsp;\u9053&nbsp;\uff0c&nbsp;\u4e0d&nbsp;\u80fd&nbsp;\u592a&nbsp;\u904e&nbsp;\u81ea&nbsp;\u4ee5&nbsp;\u70ba&nbsp;\u662f&nbsp;\uff0c&nbsp;\u4f01&nbsp;\u5716&nbsp;\u505a&nbsp;\u4e00&nbsp;\u4e9b&nbsp;\u8d85&nbsp;\u8d8a&nbsp;\u81ea&nbsp;\u7136&nbsp;\u5bb9&nbsp;\u8a31&nbsp;\u7684&nbsp;\u4e8b&nbsp;\u3002&nbsp;<br>\n\u4e00&nbsp;\u9593&nbsp;\u516c&nbsp;\u53f8&nbsp;\u7684&nbsp;\u4e3b&nbsp;\u8166&nbsp;\u4eba&nbsp;\uff0c&nbsp;\u5fc5&nbsp;\u9808&nbsp;\u5148&nbsp;\u4e86&nbsp;\u89e3&nbsp;\u4ed6&nbsp;\u6240&nbsp;\u8655&nbsp;\u7684&nbsp;\u6642&nbsp;\u7a7a&nbsp;\u74b0&nbsp;\u5883&nbsp;\uff0c&nbsp;\u77e5&nbsp;\u9053&nbsp;\u4ed6&nbsp;\u53d7&nbsp;\u7684&nbsp;\u5ba2&nbsp;\u89c0&nbsp;\u5c40&nbsp;\u9650&nbsp;\u3002&nbsp;\u9019&nbsp;\u6a23&nbsp;\u4ed6&nbsp;\u624d&nbsp;\u4e0d&nbsp;\u6703&nbsp;\u5984&nbsp;\u70ba&nbsp;\uff0c&nbsp;\u4f01&nbsp;\u5716&nbsp;\u505a&nbsp;\u4e00&nbsp;\u4e9b&nbsp;\u4ed6&nbsp;\u6839&nbsp;\u672c&nbsp;\u6c92&nbsp;\u80fd&nbsp;\u529b&nbsp;\u505a&nbsp;\u7684&nbsp;\u4e8b&nbsp;\u3002&nbsp;\u4e00&nbsp;\u500b&nbsp;\u904e&nbsp;\u4efd&nbsp;\u81ea&nbsp;\u4fe1&nbsp;\uff0c&nbsp;\u904e&nbsp;\u4efd&nbsp;\u6709&nbsp;\u70ba&nbsp;\u7684&nbsp;\u516c&nbsp;\u53f8&nbsp;\u4e3b&nbsp;\u8166&nbsp;\u4eba&nbsp;\uff0c&nbsp;\u5f88&nbsp;\u5bb9&nbsp;\u6613&nbsp;\u6309&nbsp;\u4e3b&nbsp;\u89c0&nbsp;\u610f&nbsp;\u9858&nbsp;\uff0c&nbsp;\u5236&nbsp;\u8a02&nbsp;\u4e00&nbsp;\u5957&nbsp;\u5b8f&nbsp;\u5049&nbsp;\u7684&nbsp;\u8a08&nbsp;\u5283&nbsp;\uff0c&nbsp;\u7136&nbsp;\u5f8c&nbsp;\u5f37&nbsp;\u4e0b&nbsp;\u5c6c&nbsp;\u4e4b&nbsp;\u96e3&nbsp;\uff0c&nbsp;\u903c&nbsp;\u4ed6&nbsp;\u5011&nbsp;\u70ba&nbsp;\u4ed6&nbsp;\u7684&nbsp;\u76ee&nbsp;\u7684&nbsp;\u800c&nbsp;\u4f5c&nbsp;\u51fa&nbsp;\u72a7&nbsp;\u7272&nbsp;\uff0c&nbsp;\u7d50&nbsp;\u679c&nbsp;\u5f04&nbsp;\u5230&nbsp;\u4e0b&nbsp;\u5c6c&nbsp;\u6028&nbsp;\u8072&nbsp;\u8f09&nbsp;\u9053&nbsp;\uff0c&nbsp;\u773e&nbsp;\u53db&nbsp;\u89aa&nbsp;\u96e2&nbsp;\uff0c&nbsp;\u6158&nbsp;\u6557&nbsp;\u6536&nbsp;\u5834&nbsp;\u3002&nbsp;<br>\n\u6211&nbsp;\u4ea6&nbsp;\u6253&nbsp;\u904e&nbsp;\u5de5&nbsp;\uff0c&nbsp;\u6211&nbsp;\u6df1&nbsp;\u6df1&nbsp;\u660e&nbsp;\u767d&nbsp;\uff0c&nbsp;\u7576&nbsp;\u4e00&nbsp;\u500b&nbsp;\u4eba&nbsp;\u505a&nbsp;\u81ea&nbsp;\u5df1&nbsp;\u60f3&nbsp;\u505a&nbsp;\u7684&nbsp;\u4e8b&nbsp;\u7684&nbsp;\u6642&nbsp;\u5019&nbsp;\uff0c&nbsp;\u624d&nbsp;\u9858&nbsp;\u610f&nbsp;\u5168&nbsp;\u529b&nbsp;\u4ee5&nbsp;\u8d74&nbsp;\uff0c&nbsp;\u628a&nbsp;\u81ea&nbsp;\u5df1&nbsp;\u7684&nbsp;\u5275&nbsp;\u610f&nbsp;\u5145&nbsp;\u4efd&nbsp;\u767c&nbsp;\u63ee&nbsp;\u51fa&nbsp;\u4f86&nbsp;\u3002&nbsp;\u76f8&nbsp;\u53cd&nbsp;\uff0c&nbsp;\u7576&nbsp;\u4e00&nbsp;\u500b&nbsp;\u4eba&nbsp;\u88ab&nbsp;\u4e0a&nbsp;\u53f8&nbsp;\u6240&nbsp;\u903c&nbsp;\uff0c&nbsp;\u4e0d&nbsp;\u5f97&nbsp;\u4e0d&nbsp;\u53bb&nbsp;\u505a&nbsp;\u4e00&nbsp;\u4e9b&nbsp;\u4e0d&nbsp;\u660e&nbsp;\u6240&nbsp;\u4ee5&nbsp;\uff0c&nbsp;\u751a&nbsp;\u81f3&nbsp;\u662f&nbsp;\u6c92&nbsp;\u6cd5&nbsp;\u8a8d&nbsp;\u540c&nbsp;\u7684&nbsp;\u4e8b&nbsp;\u7684&nbsp;\u6642&nbsp;\u5019&nbsp;\uff0c&nbsp;\u4ed6&nbsp;\u5fc5&nbsp;\u7136&nbsp;\u6703&nbsp;\u5f97&nbsp;\u904e&nbsp;\u4e14&nbsp;\u904e&nbsp;\uff0c&nbsp;\u7565&nbsp;\u4f5c&nbsp;\u4ea4&nbsp;\u5f85&nbsp;\u5c31&nbsp;\u7b97&nbsp;\u4e86&nbsp;\u3002&nbsp;\u6240&nbsp;\u4ee5&nbsp;\uff0c&nbsp;\u6211&nbsp;\u76e1&nbsp;\u91cf&nbsp;\u4e0d&nbsp;\u5728&nbsp;\u516c&nbsp;\u53f8&nbsp;\u8aaa&nbsp;\u6211&nbsp;\u60f3&nbsp;\u4ed6&nbsp;\u5011&nbsp;\u505a&nbsp;\u4ec0&nbsp;\u9ebc&nbsp;\uff0c&nbsp;\u600e&nbsp;\u9ebc&nbsp;\u53bb&nbsp;\u505a&nbsp;\uff0c&nbsp;\u6211&nbsp;\u53ea&nbsp;\u6703&nbsp;\u554f&nbsp;\uff0c&nbsp;\u73fe&nbsp;\u5728&nbsp;\u6211&nbsp;\u5011&nbsp;\u9762&nbsp;\u5c0d&nbsp;\u9019&nbsp;\u6a23&nbsp;\u7684&nbsp;\u74b0&nbsp;\u5883&nbsp;\uff0c&nbsp;\u4f60&nbsp;\u5011&nbsp;\u8a8d&nbsp;\u70ba&nbsp;\u61c9&nbsp;\u8a72&nbsp;\u600e&nbsp;\u9ebc&nbsp;\u8fa6&nbsp;\uff1f&nbsp;\u4ed6&nbsp;\u5011&nbsp;\u81ea&nbsp;\u5df1&nbsp;\u60f3&nbsp;\u51fa&nbsp;\u4f86&nbsp;\u7684&nbsp;\u4e3b&nbsp;\u610f&nbsp;\uff0c&nbsp;\u81ea&nbsp;\u7136&nbsp;\u5e0c&nbsp;\u671b&nbsp;\u505a&nbsp;\u51fa&nbsp;\u6210&nbsp;\u7e3e&nbsp;\u3002&nbsp;\u8981&nbsp;\u4e0b&nbsp;\u5c6c&nbsp;\u591a&nbsp;\u51fa&nbsp;\u4e3b&nbsp;\u610f&nbsp;\uff0c&nbsp;\u5fc5&nbsp;\u9808&nbsp;\u81ea&nbsp;\u5df1&nbsp;\u5c11&nbsp;\u51fa&nbsp;\u4e3b&nbsp;\u610f&nbsp;\u3002&nbsp;\u4e3b&nbsp;\u8166&nbsp;\u4eba&nbsp;\u7121&nbsp;\u70ba&nbsp;\uff0c&nbsp;\u4e0b&nbsp;\u5c6c&nbsp;\u624d&nbsp;\u80fd&nbsp;\u6709&nbsp;\u4f5c&nbsp;\u70ba&nbsp;\u3002&nbsp;\u9019&nbsp;\u6a23&nbsp;\u624d&nbsp;\u80fd&nbsp;\u505a&nbsp;\u5230&nbsp;\u8001&nbsp;\u5b50&nbsp;\u6240&nbsp;\u8aaa&nbsp;\u7684&nbsp;\uff1a&nbsp;\u300c&nbsp;\u529f&nbsp;\u6210&nbsp;\u4e8b&nbsp;\u9042&nbsp;\uff0c&nbsp;\u767e&nbsp;\u59d3&nbsp;\u7686&nbsp;\u8b02&nbsp;\u6211&nbsp;\u81ea&nbsp;\u7136&nbsp;\u3002&nbsp;\u300d&nbsp;\u5373&nbsp;\u4e0d&nbsp;\u9700&nbsp;\u767c&nbsp;\u865f&nbsp;\u53f8&nbsp;\u4ee4&nbsp;\u5c31&nbsp;\u80fd&nbsp;\u529f&nbsp;\u6210&nbsp;\u4e8b&nbsp;\u9042&nbsp;\uff0c&nbsp;\u597d&nbsp;\u50cf&nbsp;\u4e0d&nbsp;\u7528&nbsp;\u51fa&nbsp;\u592a&nbsp;\u5927&nbsp;\u7684&nbsp;\u529b&nbsp;\u6c23&nbsp;\uff0c&nbsp;\u4e8b&nbsp;\u60c5&nbsp;\u5c31&nbsp;\u81ea&nbsp;\u81ea&nbsp;\u7136&nbsp;\u7136&nbsp;\u5730&nbsp;\u505a&nbsp;\u597d&nbsp;\u4e86&nbsp;\u3002&nbsp;<br>\n\u8001&nbsp;\u5b50&nbsp;\u8aaa&nbsp;\uff1a&nbsp;\u300c&nbsp;\u9053&nbsp;\u5e38&nbsp;\u7121&nbsp;\u70ba&nbsp;\u800c&nbsp;\u7121&nbsp;\u4e0d&nbsp;\u70ba&nbsp;\u3002&nbsp;\u300d&nbsp;\u5c31&nbsp;\u662f&nbsp;\u4ee5&nbsp;\u6211&nbsp;\u5011&nbsp;\u6240&nbsp;\u8655&nbsp;\u7684&nbsp;\u81ea&nbsp;\u7136&nbsp;\u529b&nbsp;\u91cf&nbsp;\u70ba&nbsp;\u4f8b&nbsp;\uff0c&nbsp;\u81ea&nbsp;\u7136&nbsp;\u7684&nbsp;\u529b&nbsp;\u91cf&nbsp;\u4e26&nbsp;\u6c92&nbsp;\u6709&nbsp;\u523b&nbsp;\u610f&nbsp;\u8981&nbsp;\u6709&nbsp;\u4ec0&nbsp;\u9ebc&nbsp;\u4f5c&nbsp;\u70ba&nbsp;\uff0c&nbsp;\u4f46&nbsp;\u537b&nbsp;\u9020&nbsp;\u51fa&nbsp;\u9ad8&nbsp;\u5c71&nbsp;\u6d41&nbsp;\u6c34&nbsp;\uff0c&nbsp;\u9ce5&nbsp;\u8a9e&nbsp;\u82b1&nbsp;\u9999&nbsp;\uff0c&nbsp;\u7a2e&nbsp;\u7a2e&nbsp;\u4eba&nbsp;\u9593&nbsp;\u5947&nbsp;\u8de1&nbsp;\u3002&nbsp;\u5176&nbsp;\u5be6&nbsp;\u6bcf&nbsp;\u4e00&nbsp;\u500b&nbsp;\u4eba&nbsp;\u90fd&nbsp;\u79c9&nbsp;\u627f&nbsp;\u81ea&nbsp;\u7136&nbsp;\u7d66&nbsp;\u4ed6&nbsp;\u7684&nbsp;\u610f&nbsp;\u5fd7&nbsp;\u529b&nbsp;\uff0c&nbsp;\u53ea&nbsp;\u8981&nbsp;\u70ba&nbsp;\u653f&nbsp;\u8005&nbsp;\u4e0d&nbsp;\u8981&nbsp;\u5984&nbsp;\u81ea&nbsp;\u53bb&nbsp;\u64fa&nbsp;\u5e03&nbsp;\u500b&nbsp;\u4eba&nbsp;\u7684&nbsp;\u610f&nbsp;\u5fd7&nbsp;\uff0c&nbsp;\u6bcf&nbsp;\u500b&nbsp;\u500b&nbsp;\u4eba&nbsp;\u5c31&nbsp;\u81ea&nbsp;\u767c&nbsp;\u5730&nbsp;\u53bb&nbsp;\u628a&nbsp;\u81ea&nbsp;\u5df1&nbsp;\u60f3&nbsp;\u505a&nbsp;\u7684&nbsp;\u5de5&nbsp;\u4f5c&nbsp;\u505a&nbsp;\u597d&nbsp;\u3002<br>\n\u897f&nbsp;\u65b9&nbsp;\u7d93&nbsp;\u6fdf&nbsp;\u5b78&nbsp;\u5bb6&nbsp;\u4e5f&nbsp;\u6709&nbsp;\u7121&nbsp;\u5f62&nbsp;\u4e4b&nbsp;\u624b&nbsp;\u4e00&nbsp;\u8aaa&nbsp;\uff0c&nbsp;\u8a8d&nbsp;\u70ba&nbsp;\u53ea&nbsp;\u8981&nbsp;\u653f&nbsp;\u5e9c&nbsp;\u4e0d&nbsp;\u8981&nbsp;\u4efb&nbsp;\u610f&nbsp;\u5e72&nbsp;\u9810&nbsp;\u5e02&nbsp;\u5834&nbsp;\uff0c&nbsp;\u5e02&nbsp;\u5834&nbsp;\u6a5f&nbsp;\u5236&nbsp;\u81ea&nbsp;\u7136&nbsp;\u53ef&nbsp;\u4ee5&nbsp;\u5f15&nbsp;\u767c&nbsp;\u4eba&nbsp;\u5011&nbsp;\u751f&nbsp;\u7522&nbsp;\u793e&nbsp;\u6703&nbsp;\u9700&nbsp;\u8981&nbsp;\u7684&nbsp;\u7522&nbsp;\u54c1&nbsp;\uff0c&nbsp;\u63d0&nbsp;\u4f9b&nbsp;\u793e&nbsp;\u6703&nbsp;\u9700&nbsp;\u8981&nbsp;\u7684&nbsp;\u670d&nbsp;\u52d9&nbsp;\uff0c&nbsp;\u81ea&nbsp;\u7136&nbsp;\u800c&nbsp;\u7136&nbsp;\u5730&nbsp;\u589e&nbsp;\u52a0&nbsp;\u4eba&nbsp;\u985e&nbsp;\u7684&nbsp;\u798f&nbsp;\u7949&nbsp;\u3002&nbsp;\u6240&nbsp;\u8b02&nbsp;\u7121&nbsp;\u5f62&nbsp;\u4e4b&nbsp;\u624b&nbsp;\uff0c&nbsp;\u5176&nbsp;\u5be6&nbsp;\u5c31&nbsp;\u662f&nbsp;\u8001&nbsp;\u5b50&nbsp;\u6240&nbsp;\u8aaa&nbsp;\u7684&nbsp;\u9053&nbsp;\uff0c&nbsp;\u6240&nbsp;\u8b02&nbsp;\u4e0d&nbsp;\u5e72&nbsp;\u9810&nbsp;\u653f&nbsp;\u7b56&nbsp;\uff0c&nbsp;\u5176&nbsp;\u5be6&nbsp;\u5c31&nbsp;\u662f&nbsp;\u8aaa&nbsp;\u8981&nbsp;\u7121&nbsp;\u70ba&nbsp;\u800c&nbsp;\u6cbb&nbsp;\u3002&nbsp;\u7531&nbsp;\u6b64&nbsp;\u770b&nbsp;\u4f86&nbsp;\uff0c&nbsp;\u900f&nbsp;\u904e&nbsp;\u7121&nbsp;\u70ba&nbsp;\u800c&nbsp;\u6cbb&nbsp;\u800c&nbsp;\u4ee4&nbsp;\u516c&nbsp;\u53f8&nbsp;\u6210&nbsp;\u9577&nbsp;\u4e0d&nbsp;\u662f&nbsp;\u6c92&nbsp;\u6709&nbsp;\u53ef&nbsp;\u80fd&nbsp;\u7684&nbsp;\uff0c&nbsp;\u800c&nbsp;\u4e14&nbsp;\u662f&nbsp;\u529f&nbsp;\u6210&nbsp;\u4e8b&nbsp;\u9042&nbsp;\u7684&nbsp;\u5fc5&nbsp;\u7531&nbsp;\u4e4b&nbsp;\u8def&nbsp;\u3002&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u6211  \u5e38  \u544a  \u8a34  \u4eba  \uff0c  \u6211  \u4ee5  \u7121  \u70ba  \u800c  \u6cbb  \u7684  \u7406  \u5ff5  \u4f86  \u7ba1 <\/p>\n","protected":false},"author":183,"featured_media":240783,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[25703],"tags":[],"class_list":["post-246692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/posts\/246692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/users\/183"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/comments?post=246692"}],"version-history":[{"count":1,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/posts\/246692\/revisions"}],"predecessor-version":[{"id":251490,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/posts\/246692\/revisions\/251490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/media\/240783"}],"wp:attachment":[{"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/media?parent=246692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/categories?post=246692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/tags?post=246692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}