{"id":246663,"date":"1999-04-09T08:21:00","date_gmt":"1999-04-09T00:21:00","guid":{"rendered":"https:\/\/articles.ricacorp.com\/?p=246663"},"modified":"2019-02-21T11:00:23","modified_gmt":"2019-02-21T03:00:23","slug":"%e4%b8%ad%e5%9c%8b%e5%85%a5%e4%b8%96%e8%b2%bf-%e9%a6%99%e6%b8%af%e7%8d%b2%e7%9b%8a%e5%a4%9a","status":"publish","type":"post","link":"https:\/\/www.ricacorp.com.cn\/articles\/1999\/04\/09\/%e4%b8%ad%e5%9c%8b%e5%85%a5%e4%b8%96%e8%b2%bf-%e9%a6%99%e6%b8%af%e7%8d%b2%e7%9b%8a%e5%a4%9a\/","title":{"rendered":"\u4e2d\u570b\u5165\u4e16\u8cbf \u9999\u6e2f\u7372\u76ca\u591a"},"content":{"rendered":"<p>\u8207&nbsp;\u514b&nbsp;\u6797&nbsp;\u9813&nbsp;\u7e3d&nbsp;\u7d71&nbsp;\u4f5c&nbsp;\u975e&nbsp;\u6b63&nbsp;\u5f0f&nbsp;\u6703&nbsp;\u8ac7&nbsp;\u5f8c&nbsp;\uff0c&nbsp;\u6731&nbsp;\u9394&nbsp;\u57fa&nbsp;\u7e3d&nbsp;\u7406&nbsp;\u8aaa&nbsp;\uff0c&nbsp;\u7531&nbsp;\u65bc&nbsp;\u7f8e&nbsp;\u570b&nbsp;\u7684&nbsp;\u653f&nbsp;\u6cbb&nbsp;\u6c23&nbsp;\u6c1b&nbsp;\uff0c&nbsp;\u4e2d&nbsp;\u7f8e&nbsp;\u672a&nbsp;\u80fd&nbsp;\u5728&nbsp;\u4e2d&nbsp;\u570b&nbsp;\u5165&nbsp;\u4e16&nbsp;\u8cbf&nbsp;\u554f&nbsp;\u984c&nbsp;\u4e0a&nbsp;\u53d6&nbsp;\u5f97&nbsp;\u5354&nbsp;\u8b70&nbsp;\u3002&nbsp;\u4f46&nbsp;\u7f8e&nbsp;\u570b&nbsp;\u7e3d&nbsp;\u7d71&nbsp;\u537b&nbsp;\u8aaa&nbsp;\uff0c&nbsp;\u8ac7&nbsp;\u5224&nbsp;\u5df2&nbsp;\u53d6&nbsp;\u5f97&nbsp;\u91cd&nbsp;\u5927&nbsp;\u9032&nbsp;\u5c55&nbsp;\uff0c&nbsp;\u9918&nbsp;\u4e0b&nbsp;\u7684&nbsp;\u554f&nbsp;\u984c&nbsp;\u61c9&nbsp;\u53ef&nbsp;\u5728&nbsp;\u4eca&nbsp;\u5e74&nbsp;\u5167&nbsp;\u89e3&nbsp;\u6c7a&nbsp;\u3002&nbsp;\u6731&nbsp;\u9394&nbsp;\u57fa&nbsp;\u7e3d&nbsp;\u7406&nbsp;\u53c8&nbsp;\u8868&nbsp;\u793a&nbsp;\uff0c&nbsp;\u4ed6&nbsp;\u4e0d&nbsp;\u540c&nbsp;\u610f&nbsp;\u9999&nbsp;\u6e2f&nbsp;\u50b3&nbsp;\u5a92&nbsp;\u8aaa&nbsp;\u4ed6&nbsp;\u53bb&nbsp;\u7f8e&nbsp;\u570b&nbsp;\u9001&nbsp;\u5927&nbsp;\u79ae&nbsp;\u7684&nbsp;\u8a55&nbsp;\u8ad6&nbsp;\u3002&nbsp;\u4ed6&nbsp;\u8aaa&nbsp;\uff0c&nbsp;\u4e2d&nbsp;\u570b&nbsp;\u8981&nbsp;\u52a0&nbsp;\u5165&nbsp;\u4e16&nbsp;\u8cbf&nbsp;\uff0c&nbsp;\u5c31&nbsp;\u8981&nbsp;\u9075&nbsp;\u5b88&nbsp;\u4eba&nbsp;\u5bb6&nbsp;\u7684&nbsp;\u904a&nbsp;\u6232&nbsp;\u898f&nbsp;\u5247&nbsp;\uff0c&nbsp;\u4e0d&nbsp;\u80fd&nbsp;\u770b&nbsp;\u4f5c&nbsp;\u662f&nbsp;\u4e00&nbsp;\u7a2e&nbsp;\u5949&nbsp;\u737b&nbsp;\u3002&nbsp;<br>\n\u7531&nbsp;\u6b64&nbsp;\u770b&nbsp;\u4f86&nbsp;\uff0c&nbsp;\u4e2d&nbsp;\u570b&nbsp;\u5df2&nbsp;\u6c7a&nbsp;\u5fc3&nbsp;\u8abf&nbsp;\u7bc0&nbsp;\u81ea&nbsp;\u5df1&nbsp;\u76f8&nbsp;\u5c0d&nbsp;\u95dc&nbsp;\u9589&nbsp;\u7684&nbsp;\u6a5f&nbsp;\u5236&nbsp;\uff0c&nbsp;\u4ee5&nbsp;\u9069&nbsp;\u5408&nbsp;\u4e16&nbsp;\u8cbf&nbsp;\u7684&nbsp;\u8981&nbsp;\u6c42&nbsp;\uff0c&nbsp;\u800c&nbsp;\u4e14&nbsp;\u8ac7&nbsp;\u5224&nbsp;\u5df2&nbsp;\u9032&nbsp;\u5c55&nbsp;\u4e0d&nbsp;\u932f&nbsp;\uff0c&nbsp;\u76f8&nbsp;\u4fe1&nbsp;\u4e00&nbsp;\u5169&nbsp;\u5e74&nbsp;\u5167&nbsp;\u5fc5&nbsp;\u80fd&nbsp;\u89e3&nbsp;\u6c7a&nbsp;\u554f&nbsp;\u984c&nbsp;\u3002&nbsp;<br>\n\u4e2d&nbsp;\u570b&nbsp;\u5982&nbsp;\u80fd&nbsp;\u52a0&nbsp;\u5165&nbsp;\u4e16&nbsp;\u8cbf&nbsp;\u5c0d&nbsp;\u9999&nbsp;\u6e2f&nbsp;\u53ef&nbsp;\u8b02&nbsp;\u7d55&nbsp;\u8655&nbsp;\u9022&nbsp;\u751f&nbsp;\uff0c&nbsp;\u6211&nbsp;\u5011&nbsp;\u4e0d&nbsp;\u4f46&nbsp;\u53ef&nbsp;\u4ee5&nbsp;\u4e0d&nbsp;\u7528&nbsp;\u6bcf&nbsp;\u5e74&nbsp;\u90fd&nbsp;\u70ba&nbsp;\u4e2d&nbsp;\u570b&nbsp;\u80fd&nbsp;\u5426&nbsp;\u7372&nbsp;\u5f97&nbsp;\u7f8e&nbsp;\u570b&nbsp;\u7684&nbsp;\u6700&nbsp;\u60e0&nbsp;\u570b&nbsp;\u5f85&nbsp;\u9047&nbsp;\u800c&nbsp;\u64d4&nbsp;\u6182&nbsp;\uff0c&nbsp;\u7576&nbsp;\u4e16&nbsp;\u8cbf&nbsp;\u7684&nbsp;\u5354&nbsp;\u8b70&nbsp;\u5168&nbsp;\u9762&nbsp;\u5be6&nbsp;\u65bd&nbsp;\u5f8c&nbsp;\uff0c&nbsp;\u6210&nbsp;\u54e1&nbsp;\u570b&nbsp;\u4e4b&nbsp;\u9593&nbsp;\u7684&nbsp;\u8cbf&nbsp;\u6613&nbsp;\u5c07&nbsp;\u4e0d&nbsp;\u8a2d&nbsp;\u95dc&nbsp;\u7a05&nbsp;\u3002&nbsp;\u9019&nbsp;\u5c07&nbsp;\u6380&nbsp;\u8d77&nbsp;\u65b0&nbsp;\u4e00&nbsp;\u8f2a&nbsp;\u7684&nbsp;\u6295&nbsp;\u8cc7&nbsp;\u4e2d&nbsp;\u570b&nbsp;\u5927&nbsp;\u9678&nbsp;\u7684&nbsp;\u71b1&nbsp;\u6f6e&nbsp;\uff0c&nbsp;\u9999&nbsp;\u6e2f&nbsp;\u5c07&nbsp;\u53ef&nbsp;\u4ee5&nbsp;\u5206&nbsp;\u5230&nbsp;\u4e00&nbsp;\u676f&nbsp;\u7fb9&nbsp;\u3002&nbsp;<br>\n\u73fe&nbsp;\u6642&nbsp;\u5916&nbsp;\u8cc7&nbsp;\u9084&nbsp;\u4e0d&nbsp;\u6562&nbsp;\u5927&nbsp;\u91cf&nbsp;\u9032&nbsp;\u5165&nbsp;\u4e2d&nbsp;\u570b&nbsp;\u6295&nbsp;\u8cc7&nbsp;\uff0c&nbsp;\u56e0&nbsp;\u70ba&nbsp;\u5728&nbsp;\u4e2d&nbsp;\u570b&nbsp;\u6295&nbsp;\u8cc7&nbsp;\u7684&nbsp;\u7522&nbsp;\u54c1&nbsp;\u53ea&nbsp;\u80fd&nbsp;\u5916&nbsp;\u92b7&nbsp;\uff0c&nbsp;\u4e0d&nbsp;\u6e96&nbsp;\u5167&nbsp;\u92b7&nbsp;\u6216&nbsp;\u53ea&nbsp;\u5bb9&nbsp;\u8a31&nbsp;\u5c11&nbsp;\u90e8&nbsp;\u5206&nbsp;\u5167&nbsp;\u92b7&nbsp;\uff0c&nbsp;\u4ee5&nbsp;\u514d&nbsp;\u8207&nbsp;\u570b&nbsp;\u7522&nbsp;\u5546&nbsp;\u54c1&nbsp;\u7af6&nbsp;\u722d&nbsp;\uff0c&nbsp;\u4f46&nbsp;\u7531&nbsp;\u65bc&nbsp;\u4e2d&nbsp;\u570b&nbsp;\u672c&nbsp;\u8eab&nbsp;\u5916&nbsp;\u8cbf&nbsp;\u4e0d&nbsp;\u958b&nbsp;\u653e&nbsp;\uff0c&nbsp;\u5176&nbsp;\u4ed6&nbsp;\u570b&nbsp;\u5bb6&nbsp;\u5c31&nbsp;\u5c0d&nbsp;\u4e2d&nbsp;\u570b&nbsp;\u7684&nbsp;\u7522&nbsp;\u54c1&nbsp;\uff0c&nbsp;\u5305&nbsp;\u62ec&nbsp;\u5916&nbsp;\u5546&nbsp;\u6295&nbsp;\u8cc7&nbsp;\u7684&nbsp;\uff0c&nbsp;\u5be6&nbsp;\u65bd&nbsp;\u914d&nbsp;\u984d&nbsp;\u5236&nbsp;\u5ea6&nbsp;\uff0c&nbsp;\u6216&nbsp;\u4ee5&nbsp;\u5fb5&nbsp;\u6536&nbsp;\u9ad8&nbsp;\u95dc&nbsp;\u7a05&nbsp;\u4f5c&nbsp;\u56de&nbsp;\u61c9&nbsp;\uff0c&nbsp;\u9019&nbsp;\u5927&nbsp;\u5927&nbsp;\u62b5&nbsp;\u6d88&nbsp;\u4e86&nbsp;\u5728&nbsp;\u4e2d&nbsp;\u570b&nbsp;\u751f&nbsp;\u7522&nbsp;\u6210&nbsp;\u672c&nbsp;\u4f4e&nbsp;\u7684&nbsp;\u5438&nbsp;\u5f15&nbsp;\u529b&nbsp;\u3002&nbsp;\u4f46&nbsp;\u4e2d&nbsp;\u570b&nbsp;\u52a0&nbsp;\u5165&nbsp;\u4e16&nbsp;\u8cbf&nbsp;\u5f8c&nbsp;\uff0c&nbsp;\u4e2d&nbsp;\u570b&nbsp;\u51fa&nbsp;\u53e3&nbsp;\u53bb&nbsp;\u4e16&nbsp;\u8cbf&nbsp;\u7684&nbsp;\u6210&nbsp;\u54e1&nbsp;\u570b&nbsp;\uff0c&nbsp;\u5c07&nbsp;\u4e0d&nbsp;\u53d7&nbsp;\u914d&nbsp;\u984d&nbsp;\u53ca&nbsp;\u95dc&nbsp;\u7a05&nbsp;\u7684&nbsp;\u9650&nbsp;\u5236&nbsp;\u3002&nbsp;\u5927&nbsp;\u90e8&nbsp;\u5206&nbsp;\u6b50&nbsp;\u7f8e&nbsp;\u570b&nbsp;\u5bb6&nbsp;\u90fd&nbsp;\u662f&nbsp;\u4e16&nbsp;\u8cbf&nbsp;\u7684&nbsp;\u6210&nbsp;\u54e1&nbsp;\u570b&nbsp;\uff0c&nbsp;\u4ed6&nbsp;\u5011&nbsp;\u662f&nbsp;\u4e2d&nbsp;\u570b&nbsp;\u7684&nbsp;\u4e3b&nbsp;\u8981&nbsp;\u51fa&nbsp;\u53e3&nbsp;\u570b&nbsp;\uff0c&nbsp;\u5728&nbsp;\u6c92&nbsp;\u6709&nbsp;\u914d&nbsp;\u984d&nbsp;\u53ca&nbsp;\u95dc&nbsp;\u7a05&nbsp;\u7684&nbsp;\u9650&nbsp;\u5236&nbsp;\u4e0b&nbsp;\uff0c&nbsp;\u4e2d&nbsp;\u570b&nbsp;\u5c0d&nbsp;\u9019&nbsp;\u4e9b&nbsp;\u570b&nbsp;\u5bb6&nbsp;\u7684&nbsp;\u51fa&nbsp;\u53e3&nbsp;\u80fd&nbsp;\u529b&nbsp;\u5c07&nbsp;\u9032&nbsp;\u4e00&nbsp;\u6b65&nbsp;\u767c&nbsp;\u63ee&nbsp;\u3002&nbsp;<br>\n\u9019&nbsp;\u5373&nbsp;\u662f&nbsp;\u8aaa&nbsp;\uff0c&nbsp;\u52a0&nbsp;\u5165&nbsp;\u4e16&nbsp;\u8cbf&nbsp;\u5f8c&nbsp;\uff0c&nbsp;\u5728&nbsp;\u4e2d&nbsp;\u570b&nbsp;\u8a2d&nbsp;\u5ee0&nbsp;\u6240&nbsp;\u751f&nbsp;\u7522&nbsp;\u51fa&nbsp;\u4f86&nbsp;\u5546&nbsp;\u54c1&nbsp;\uff0c&nbsp;\u5c07&nbsp;\u6703&nbsp;\u7372&nbsp;\u5f97&nbsp;\u5728&nbsp;\u4e16&nbsp;\u8cbf&nbsp;\u5176&nbsp;\u4ed6&nbsp;\u6210&nbsp;\u54e1&nbsp;\u570b&nbsp;\u8a2d&nbsp;\u5ee0&nbsp;\u7684&nbsp;\u540c&nbsp;\u4e00&nbsp;\u5f85&nbsp;\u9047&nbsp;\uff0c&nbsp;\u90a3&nbsp;\u6295&nbsp;\u8cc7&nbsp;\u8005&nbsp;\u5fc5&nbsp;\u7136&nbsp;\u6703&nbsp;\u628a&nbsp;\u8cc7&nbsp;\u91d1&nbsp;\u6295&nbsp;\u5230&nbsp;\u6210&nbsp;\u672c&nbsp;\u8f03&nbsp;\u4f4e&nbsp;\u7684&nbsp;\u4e2d&nbsp;\u570b&nbsp;\u4f86&nbsp;\u3002&nbsp;<br>\n\u5916&nbsp;\u8cc7&nbsp;\u8981&nbsp;\u5165&nbsp;\u4e2d&nbsp;\u570b&nbsp;\uff0c&nbsp;\u5fc5&nbsp;\u7136&nbsp;\u6703&nbsp;\u5229&nbsp;\u7528&nbsp;\u9999&nbsp;\u6e2f&nbsp;\u4eba&nbsp;\u4f5c&nbsp;\u7a7f&nbsp;\u91dd&nbsp;\u5f15&nbsp;\u7dda&nbsp;\uff0c&nbsp;\u90a3&nbsp;\u9999&nbsp;\u6e2f&nbsp;\u4f5c&nbsp;\u70ba&nbsp;\u64ae&nbsp;\u5408&nbsp;\u751f&nbsp;\u610f&nbsp;\u7684&nbsp;\u7d93&nbsp;\u7d00&nbsp;\u4eba&nbsp;\u7684&nbsp;\u529f&nbsp;\u80fd&nbsp;\u5c31&nbsp;\u80fd&nbsp;\u767c&nbsp;\u63ee&nbsp;\u3002&nbsp;\u9999&nbsp;\u6e2f&nbsp;\u4eba&nbsp;\u5411&nbsp;\u4f86&nbsp;\u512a&nbsp;\u65bc&nbsp;\u6b64&nbsp;\u9053&nbsp;\uff0c&nbsp;\u4e0d&nbsp;\u7528&nbsp;\u6709&nbsp;\u6700&nbsp;\u5148&nbsp;\u9032&nbsp;\u7684&nbsp;\u79d1&nbsp;\u6280&nbsp;\u77e5&nbsp;\u8b58&nbsp;\u4e5f&nbsp;\u80fd&nbsp;\u505a&nbsp;\u5f97&nbsp;\u5230&nbsp;\u3002&nbsp;<br>\n\u5916&nbsp;\u8cc7&nbsp;\u4e00&nbsp;\u4f86&nbsp;\uff0c&nbsp;\u9999&nbsp;\u6e2f&nbsp;\u4f5c&nbsp;\u70ba&nbsp;\u4e2d&nbsp;\u570b&nbsp;\u7684&nbsp;\u91d1&nbsp;\u878d&nbsp;\u8cbf&nbsp;\u6613&nbsp;\u4e2d&nbsp;\u5fc3&nbsp;\u7684&nbsp;\u5730&nbsp;\u4f4d&nbsp;\u5c31&nbsp;\u6703&nbsp;\u66f4&nbsp;\u70ba&nbsp;\u978f&nbsp;\u56fa&nbsp;\uff0c&nbsp;\u670d&nbsp;\u52d9&nbsp;\u6027&nbsp;\u884c&nbsp;\u696d&nbsp;\u8207&nbsp;\u623f&nbsp;\u5730&nbsp;\u7522&nbsp;\u696d&nbsp;\u4e0d&nbsp;\u6101&nbsp;\u597d&nbsp;\u4e0d&nbsp;\u8d77&nbsp;\u4f86&nbsp;\u3002&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u8207  \u514b  \u6797  \u9813  \u7e3d  \u7d71  \u4f5c  \u975e  \u6b63  \u5f0f  \u6703  \u8ac7  \u5f8c  \uff0c  \u6731  \u9394  \u57fa <\/p>\n","protected":false},"author":183,"featured_media":240783,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[25703],"tags":[],"class_list":["post-246663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/posts\/246663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/users\/183"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/comments?post=246663"}],"version-history":[{"count":1,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/posts\/246663\/revisions"}],"predecessor-version":[{"id":251511,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/posts\/246663\/revisions\/251511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/media\/240783"}],"wp:attachment":[{"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/media?parent=246663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/categories?post=246663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ricacorp.com.cn\/articles\/wp-json\/wp\/v2\/tags?post=246663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}